{"id":1629,"date":"2026-02-01T11:57:19","date_gmt":"2026-02-01T09:57:19","guid":{"rendered":"https:\/\/fundacioacsar.org\/projecte\/garantint-el-dret-a-la-salut-i-la-proteccio-davant-les-violencies-a-nabatieh\/"},"modified":"2026-04-15T11:11:10","modified_gmt":"2026-04-15T09:11:10","slug":"garantizando-el-derecho-a-la-salud-y-la-proteccion-frente-a-las-violencias-en-nabatieh","status":"publish","type":"projecte","link":"https:\/\/fundacioacsar.org\/es\/projecte\/garantizando-el-derecho-a-la-salud-y-la-proteccion-frente-a-las-violencias-en-nabatieh\/","title":{"rendered":"Garantizando el derecho a la salud y la protecci\u00f3n frente a las violencias en Nabatieh"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-justify-content-center fusion-flex-content-wrap\" style=\"max-width:1248px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\"><p><strong>Per\u00edodo de ejecuci\u00f3n: 2026-2028<\/strong><\/p>\n<p>El proyecto propuesto contribuye al ejercicio efectivo del derecho a la salud y a una vida libre de violencias de las mujeres, la infancia y la poblaci\u00f3n refugiada y libanesa en situaci\u00f3n de vulnerabilidad en el gobernadorado de Nabatieh, en el sur del L\u00edbano. Esta propuesta da continuidad a las dos fases anteriores desarrolladas por el Socorro Popular Liban\u00e9s (SPL), la Asociaci\u00f3n Catalu\u00f1a-L\u00edbano (ACL) y la Fundaci\u00f3n ACSAR, y surge de las necesidades detectadas conjuntamente con los colectivos protagonistas, en el marco de un contexto agravado por el colapso de los servicios p\u00fablicos, la crisis socioecon\u00f3mica y las nuevas tensiones en el sur del pa\u00eds.<\/p>\n<p>A partir de un EGiBDH, e integrando las dimensiones sociales, ambientales e institucionales de la salud, el proyecto se orienta a transformar las desigualdades estructurales que atraviesan el acceso a los servicios de salud y protecci\u00f3n, especialmente para mujeres, infancia y personas desplazadas. As\u00ed, el proyecto considera la VBG, la discriminaci\u00f3n y la desprotecci\u00f3n infantil como determinantes sociales centrales que vulneran el derecho a la salud. En este sentido, todas las acciones han sido dise\u00f1adas para mejorar la accesibilidad, aceptabilidad, calidad y sostenibilidad de los servicios, promoviendo la participaci\u00f3n activa de los colectivos titulares de derechos y fortaleciendo las responsabilidades y obligaciones institucionales a escala local y nacional.<\/p>\n<p>El proyecto reconoce tambi\u00e9n la dimensi\u00f3n ambiental como un determinante clave de la salud. Por ello, incluye acciones de sensibilizaci\u00f3n sobre la relaci\u00f3n entre salud y sostenibilidad, as\u00ed como mejoras en la gesti\u00f3n de residuos del Hospital Al Najda, como parte de un proceso m\u00e1s amplio de transici\u00f3n ecosocial. La propuesta se alinea con las estrategias del Regional Refugee and Resilience Plan (3RP) 2025 y del Lebanon Crisis Response Plan (LCRP 2022-23), as\u00ed como con la Estrategia Ministerial de Salud de respuesta a la situaci\u00f3n humanitaria y con los objetivos de la Agenda 2030 (ODS 3.8, 5.2, 5.3, 5.6 y 10.7).<\/p>\n<p>Los colectivos protagonistas del proyecto se distribuyen seg\u00fan el enfoque EGiBDH: las TD son mujeres, infancia y personas refugiadas o desplazadas internas, especialmente aquellas que viven en condiciones de precariedad extrema. Las TR incluyen al personal sanitario y comunitario del SPL, las escuelas locales y las entidades impulsoras. Los TO son los ayuntamientos de Nabatieh y municipios vecinos, el Ministerio de Salud P\u00fablica y el Ministerio de Asuntos Sociales libaneses, as\u00ed como el \u00c1rea de Relaciones Internacionales y Cooperaci\u00f3n del Departamento de Salud de la Generalitat de Catalu\u00f1a.<br \/>\nPara alcanzar el objetivo espec\u00edfico de fortalecer los servicios integrales de salud y protecci\u00f3n, el proyecto se estructura en cuatro resultados complementarios:<\/p>\n<p>El primer resultado mejora la disponibilidad, accesibilidad y calidad de los servicios sanitarios mediante el fortalecimiento del Hospital Al Najda, con la adquisici\u00f3n de equipamiento m\u00e9dico, dotaci\u00f3n de suministros y contrataci\u00f3n de personal sanitario.<\/p>\n<p>El segundo resultado refuerza la red comunitaria de salud a trav\u00e9s de la puesta en marcha de una Unidad M\u00e9dica M\u00f3vil, la dotaci\u00f3n de materiales y la formaci\u00f3n de tres equipos comunitarios que permitan mejorar la derivaci\u00f3n y la atenci\u00f3n en zonas alejadas y sin servicios estables.<\/p>\n<p>El tercer resultado se centra en la prevenci\u00f3n y el abordaje comunitario de las VBG. Incluye la rehabilitaci\u00f3n del Pink Center como espacio seguro para mujeres e infancia, la creaci\u00f3n y aplicaci\u00f3n de un protocolo espec\u00edfico para la atenci\u00f3n de mujeres supervivientes en situaci\u00f3n de riesgo, la formaci\u00f3n del personal sanitario y comunitario, y el refuerzo de los servicios de acompa\u00f1amiento psicosocial y de atenci\u00f3n a la SSR.<\/p>\n<p>El cuarto resultado busca incrementar las capacidades de los colectivos protagonistas para promover la salud comunitaria y la protecci\u00f3n de derechos, especialmente de la infancia y de las mujeres. Se llevar\u00e1n a cabo actividades de apoyo psicosocial, formaci\u00f3n a personas cuidadoras como agentes protectores y acciones de incidencia a nivel local, nacional e internacional. Esta dimensi\u00f3n se vincula tambi\u00e9n al fortalecimiento de redes de solidaridad e intercambio entre el L\u00edbano y Catalu\u00f1a, con la participaci\u00f3n del tercer sector catal\u00e1n.<\/p>\n<p>En conjunto, esta propuesta articula una respuesta integral, feminista y transformadora ante las m\u00faltiples vulneraciones de derechos que afectan a la poblaci\u00f3n m\u00e1s vulnerable en el L\u00edbano, con el objetivo de contribuir a una sociedad m\u00e1s justa, equitativa y libre de violencias.<\/p>\n<\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-section-separator section-separator triangle fusion-section-separator-1\" style=\"--awb-border-top:1px solid var(--awb-color3);--awb-spacer-height:1px;--awb-svg-margin-left:1.92%;--awb-svg-margin-right:1.92%;--awb-svg-margin-left-medium:1.92%;--awb-svg-margin-right-medium:1.92%;--awb-svg-margin-left-small:1.92%;--awb-svg-margin-right-small:1.92%;--awb-icon-color:var(--awb-color1);\"><div class=\"fusion-section-separator-svg\"><div class=\"divider-candy-arrow top\" style=\"bottom:0px;border-bottom-color: var(--awb-color2);\"><\/div><div class=\"divider-candy top\" style=\"top:-21px;border-bottom:1px solid var(--awb-color3);border-left:1px solid var(--awb-color3);\"><\/div><\/div><div class=\"fusion-section-separator-spacer\"><div class=\"fusion-section-separator-spacer-height\"><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-2 fusion_builder_column_1_3 1_3 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:33.333333333333%;--awb-margin-top-large:0px;--awb-spacing-right-large:5.76%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:5.76%;--awb-width-medium:33.333333333333%;--awb-order-medium:0;--awb-spacing-right-medium:5.76%;--awb-spacing-left-medium:5.76%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-2\" style=\"--awb-content-alignment:center;\"><p><strong>Donante<\/strong><\/p>\n<\/div><div class=\"fusion-image-element \" style=\"--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-1 hover-type-none\"><img decoding=\"async\" width=\"300\" height=\"214\" title=\"harm_accd_gencat_CA-vert-fonsTransp\" src=\"https:\/\/fundacioacsar.org\/wp-content\/uploads\/2026\/01\/harm_accd_gencat_CA-vert-fonsTransp-300x214.png\" alt class=\"img-responsive wp-image-1668\" srcset=\"https:\/\/fundacioacsar.org\/wp-content\/uploads\/2026\/01\/harm_accd_gencat_CA-vert-fonsTransp-200x143.png 200w, https:\/\/fundacioacsar.org\/wp-content\/uploads\/2026\/01\/harm_accd_gencat_CA-vert-fonsTransp.png 303w\" sizes=\"(max-width: 640px) 100vw, 300px\" \/><\/span><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-3 fusion_builder_column_1_3 1_3 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:33.333333333333%;--awb-margin-top-large:0px;--awb-spacing-right-large:5.76%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:5.76%;--awb-width-medium:33.333333333333%;--awb-order-medium:0;--awb-spacing-right-medium:5.76%;--awb-spacing-left-medium:5.76%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-3\" style=\"--awb-content-alignment:center;\"><p><strong>Entidad l\u00edder<\/strong><\/p>\n<\/div><div class=\"fusion-image-element \" style=\"--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-2 hover-type-none\"><img decoding=\"async\" width=\"300\" height=\"205\" title=\"Logo-acl-RGB_Color-positiu\" src=\"https:\/\/fundacioacsar.org\/wp-content\/uploads\/2026\/01\/Logo-acl-RGB_Color-positiu-300x205.jpg\" alt class=\"img-responsive wp-image-1670\" srcset=\"https:\/\/fundacioacsar.org\/wp-content\/uploads\/2026\/01\/Logo-acl-RGB_Color-positiu-200x137.jpg 200w, https:\/\/fundacioacsar.org\/wp-content\/uploads\/2026\/01\/Logo-acl-RGB_Color-positiu-400x274.jpg 400w, https:\/\/fundacioacsar.org\/wp-content\/uploads\/2026\/01\/Logo-acl-RGB_Color-positiu-600x410.jpg 600w, https:\/\/fundacioacsar.org\/wp-content\/uploads\/2026\/01\/Logo-acl-RGB_Color-positiu-800x547.jpg 800w, https:\/\/fundacioacsar.org\/wp-content\/uploads\/2026\/01\/Logo-acl-RGB_Color-positiu-1200x821.jpg 1200w, https:\/\/fundacioacsar.org\/wp-content\/uploads\/2026\/01\/Logo-acl-RGB_Color-positiu.jpg 1379w\" sizes=\"(max-width: 640px) 100vw, 400px\" \/><\/span><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"featured_media":1631,"template":"","meta":{"_acf_changed":false,"footnotes":""},"categoria-projecte":[42],"class_list":["post-1629","projecte","type-projecte","status-publish","has-post-thumbnail","hentry","categoria-projecte-cooperacion"],"acf":[],"_links":{"self":[{"href":"https:\/\/fundacioacsar.org\/es\/wp-json\/wp\/v2\/projecte\/1629","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fundacioacsar.org\/es\/wp-json\/wp\/v2\/projecte"}],"about":[{"href":"https:\/\/fundacioacsar.org\/es\/wp-json\/wp\/v2\/types\/projecte"}],"version-history":[{"count":3,"href":"https:\/\/fundacioacsar.org\/es\/wp-json\/wp\/v2\/projecte\/1629\/revisions"}],"predecessor-version":[{"id":1635,"href":"https:\/\/fundacioacsar.org\/es\/wp-json\/wp\/v2\/projecte\/1629\/revisions\/1635"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fundacioacsar.org\/es\/wp-json\/wp\/v2\/media\/1631"}],"wp:attachment":[{"href":"https:\/\/fundacioacsar.org\/es\/wp-json\/wp\/v2\/media?parent=1629"}],"wp:term":[{"taxonomy":"categoria-projecte","embeddable":true,"href":"https:\/\/fundacioacsar.org\/es\/wp-json\/wp\/v2\/categoria-projecte?post=1629"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}