{"id":1736,"date":"2013-03-25T13:01:22","date_gmt":"2013-03-25T11:01:22","guid":{"rendered":"https:\/\/fundacioacsar.org\/projecte\/jornades-sobre-asil-per-motius-dorientacio-sexual-i-de-genere-13-edicions\/"},"modified":"2026-04-15T12:36:07","modified_gmt":"2026-04-15T10:36:07","slug":"jornadas-sobre-asilo-por-motivos-de-orientacion-sexual-y-de-genero","status":"publish","type":"projecte","link":"https:\/\/fundacioacsar.org\/es\/projecte\/jornadas-sobre-asilo-por-motivos-de-orientacion-sexual-y-de-genero\/","title":{"rendered":"Jornadas sobre asilo por motivos de orientaci\u00f3n sexual y de g\u00e9nero"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-justify-content-center fusion-flex-content-wrap\" style=\"max-width:1248px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\"><div class=\"\">\n<p><strong>Per\u00edodo de ejecuci\u00f3n: 2013-actualidad<\/strong><\/p>\n<p data-start=\"152\" data-end=\"736\">Las Jornadas sobre el Derecho de Asilo por Motivos de Orientaci\u00f3n Sexual e Identidad de G\u00e9nero, impulsadas por la Fundaci\u00f3n ACSAR desde el a\u00f1o 2013, se han consolidado como un espacio de referencia en Catalu\u00f1a para visibilizar, analizar y sensibilizar sobre los desaf\u00edos interseccionales que afrontan las personas migrantes LGTBIQ+ en el acceso a la protecci\u00f3n internacional. Con m\u00e1s de una d\u00e9cada de trayectoria y 13 ediciones realizadas, estas jornadas ofrecen una mirada cr\u00edtica y actualizada sobre la doble vulneraci\u00f3n de derechos vinculada a la migraci\u00f3n y a la diversidad sexual y de g\u00e9nero.<\/p>\n<p data-start=\"738\" data-end=\"1102\">A lo largo de los a\u00f1os, las jornadas han abordado tem\u00e1ticas diversas y emergentes \u2014como el auge de la extrema derecha y los discursos de odio, las migraciones trans, el papel de la religi\u00f3n o las violencias espec\u00edficas en diferentes contextos geopol\u00edticos\u2014 manteniendo siempre el foco en la defensa de los derechos humanos y la necesidad de respuestas institucionales y sociales adecuadas.<\/p>\n<p data-start=\"1104\" data-end=\"1725\">Este espacio re\u00fane a una amplia diversidad de actores: profesionales del \u00e1mbito del asilo y la protecci\u00f3n internacional, personal t\u00e9cnico de administraciones p\u00fablicas, juristas, acad\u00e9micos, estudiantes, entidades sociales y organizaciones de defensa de los derechos LGTBIQ+, as\u00ed como activistas y personas del propio colectivo migrante. La participaci\u00f3n de entidades locales e internacionales enriquece el debate y favorece el intercambio de conocimiento, experiencias y buenas pr\u00e1cticas. En algunas ediciones, las jornadas han contado tambi\u00e9n con la colaboraci\u00f3n de instituciones como el Centre d\u2019Estudis Jur\u00eddics i Formaci\u00f3 Especialitzada (CEJFE).<\/p>\n<p data-start=\"1727\" data-end=\"2165\">El formato combina conferencias, mesas redondas y espacios participativos que permiten profundizar en las discriminaciones estructurales y cis-heteropatriarcales presentes en los procedimientos de asilo, al tiempo que impulsan propuestas para mejorar los mecanismos de protecci\u00f3n. La difusi\u00f3n posterior de los contenidos a trav\u00e9s de canales digitales contribuye a ampliar su alcance y a facilitar el acceso al conocimiento generado m\u00e1s all\u00e1 del espacio presencial.<\/p>\n<\/div>\n<\/div><div style=\"text-align:center;\"><a class=\"fusion-button button-flat fusion-button-default-size button-default fusion-button-default button-1 fusion-button-default-span fusion-button-default-type\" target=\"_self\" href=\"https:\/\/fundacioacsar.org\/es\/activitat\/xii-jornada-sobre-asilo-por-motivos-de-orientacion-sexual-e-identidad-de-genero\/\"><span class=\"fusion-button-text awb-button__text awb-button__text--default\">Consulta la \u00faltima edici\u00f3n<\/span><\/a><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><\/div><\/div><\/div><\/div>\n","protected":false},"featured_media":1738,"template":"","meta":{"_acf_changed":false,"footnotes":""},"categoria-projecte":[43],"class_list":["post-1736","projecte","type-projecte","status-publish","has-post-thumbnail","hentry","categoria-projecte-educacion-para-la-justicia-global"],"acf":[],"_links":{"self":[{"href":"https:\/\/fundacioacsar.org\/es\/wp-json\/wp\/v2\/projecte\/1736","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fundacioacsar.org\/es\/wp-json\/wp\/v2\/projecte"}],"about":[{"href":"https:\/\/fundacioacsar.org\/es\/wp-json\/wp\/v2\/types\/projecte"}],"version-history":[{"count":2,"href":"https:\/\/fundacioacsar.org\/es\/wp-json\/wp\/v2\/projecte\/1736\/revisions"}],"predecessor-version":[{"id":1762,"href":"https:\/\/fundacioacsar.org\/es\/wp-json\/wp\/v2\/projecte\/1736\/revisions\/1762"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fundacioacsar.org\/es\/wp-json\/wp\/v2\/media\/1738"}],"wp:attachment":[{"href":"https:\/\/fundacioacsar.org\/es\/wp-json\/wp\/v2\/media?parent=1736"}],"wp:term":[{"taxonomy":"categoria-projecte","embeddable":true,"href":"https:\/\/fundacioacsar.org\/es\/wp-json\/wp\/v2\/categoria-projecte?post=1736"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}